{"id":388223,"date":"2023-08-30T09:55:49","date_gmt":"2023-08-30T09:57:07","guid":{"rendered":"https:\/\/hurghadalovers.com\/shop\/senza-categoria\/noleggio-motoscafo-nella-baia-di-makadi-per-la-dolphin-house-e-lisola-di-orange-bay\/"},"modified":"2026-02-08T09:39:03","modified_gmt":"2026-02-08T09:39:03","slug":"makadi-bay-noleggio-di-motoscafi-per-la-casa-dei-delfini-orange-bay-isola","status":"publish","type":"product","link":"https:\/\/hurghadalovers.com\/it\/tours\/makadi-bay-noleggio-di-motoscafi-per-la-casa-dei-delfini-orange-bay-isola\/","title":{"rendered":"Noleggio motoscafo nella baia di Makadi per la Dolphin House e l&#8217;isola di Orange Bay"},"content":{"rendered":"<p><strong>Makadi Bay<\/strong> <strong>Speedboat Rental to Dolphin House &amp; Orange bay Island | Barche private di lusso <\/strong>con biglietti, snorkeling, bevande e trasferimento.<\/p>\n<p style=\"text-align: center;\"><span style=\"color: #00ccff;\">La pi\u00f9 bella baia di Makadi <strong>Attivit\u00e0 per famiglie<\/strong>, <strong>cose da fare con bambini<\/strong>, anziani, <strong>luna di miele<\/strong> e <strong>coppie<\/strong>.<\/span><\/p>\n<p><strong>Punti salienti:<\/strong><\/p>\n<ul>\n<li>Un punto per lo snorkeling e l&#8217;osservazione dei delfini.<\/li>\n<\/ul>\n<ul>\n<li>uno Spot Snorkeling House Reef.<\/li>\n<li>2-5 ore a Orange Bay Island Beach.<\/li>\n<\/ul>\n<p><strong>Dettagli:<\/strong><\/p>\n<ul>\n<li>Disponibilit\u00e0 del tour: Tutti i giorni.<\/li>\n<li>Tipo di tour: Privato.<\/li>\n<li>Orario di ritiro: a partire dalle 08:30 o dalle 12:30.<\/li>\n<li>Orario di partenza: 13:00 o 18:00.<\/li>\n<li>Accessibile con sedia a rotelle.<\/li>\n<li>Durata: 4-5 ore.<\/li>\n<\/ul>\n<p><strong>Prenota ora e paga dopo:<\/strong><\/p>\n<ul>\n<li>Contanti in loco per la guida.<\/li>\n<li>Pagamento in sterline egiziane, $, \u20ac o \u00a3.<\/li>\n<\/ul>\n<p><strong>Politica di cancellazione:<\/strong><\/p>\n<ul>\n<li>\u00e8 possibile effettuare la cancellazione con un anticipo di 24 ore.<\/li>\n<li>Quando qualcuno della vostra famiglia cancella la mattinata, paga il 50% del costo.<\/li>\n<\/ul>\n<p><strong>Cosa \u00e8 incluso?<\/strong><\/p>\n<ul>\n<li>Trasferimento dagli hotel della baia di Makadi &#8220;Hotel pick up and drop off&#8221;.<\/li>\n<li>Tutte le tasse, i biglietti d&#8217;ingresso e le spese di gestione.<\/li>\n<li>Acqua minerale + Cola.<\/li>\n<li>un punto di snorkeling.<\/li>\n<li>Un punto per lo snorkeling e l&#8217;osservazione dei delfini.<\/li>\n<li>Attrezzatura per lo snorkeling &#8220;Maschere e pinne&#8221;.<\/li>\n<li>2-5 ore a <strong>Orange Bay Island<\/strong> <strong>Beach<\/strong>.<\/li>\n<\/ul>\n<p><strong>Esclusioni?<\/strong><\/p>\n<ul>\n<li>Mancia.<\/li>\n<li>Bevande al ristorante Orange Bay Island.<\/li>\n<li>Eventuali extra non menzionati.<\/li>\n<\/ul>\n<p><strong>Prezzi:<\/strong><\/p>\n<ul>\n<li><strong>con Biglietti &#8220;2 persone&#8221;= 230$.<\/strong><\/li>\n<li><strong>Fino a 2 persone Biglietto extra = 5$ a persona.<\/strong><\/li>\n<\/ul>\n<p><strong>Recensioni:<\/strong><\/p>\n<p>controllate le nostre recensioni su Google Map come miglior <a href=\"https:\/\/g.page\/r\/CUeYvkngP3wkEBM\/review\">tour operator di Hurghada<\/a> online a <a href=\"https:\/\/hurghadalovers.com\/\">Hurghada<\/a> in Egitto.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Prenotazione:<\/strong><\/p>\n<p>Invia hotel + numero di camera + foto passaporto a WhatsApp: <strong>+201112596434<\/strong><\/p>\n<p>Se sei in Egitto Prenota ora online e conferma all&#8217;arrivo Hotel.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p><strong>Makadi Bay<\/strong> <strong>Speedboat Rental to Dolphin House &amp; Orange bay Island | Barche private di lusso <\/strong>con biglietti, snorkeling, bevande e trasferimento.<\/p>\n","protected":false},"featured_media":388145,"template":"","meta":{"_joinchat":[]},"product_brand":[],"product_cat":[29297],"product_tag":[],"class_list":{"0":"post-388223","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-egypt-tours","7":"tour_category-things-to-do-in-makadi-bay-italian","8":"tour_category-makadi-bay-snorkeling-trips-italian","10":"first","11":"instock","12":"sale","13":"shipping-taxable","14":"purchasable","15":"product-type-tour"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.9 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Noleggio motoscafo a Makadi Bay per Dolphin House e Orange Bay<\/title>\n<meta name=\"description\" content=\"Makadi Bay Speedboat Rental to Dolphin House &amp; Orange bay Island | Barche private di lusso con biglietti, snorkeling, bevande e trasferimento.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hurghadalovers.com\/it\/tours\/makadi-bay-noleggio-di-motoscafi-per-la-casa-dei-delfini-orange-bay-isola\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Noleggio motoscafo nella baia di Makadi per la Dolphin House e l&#039;isola di Orange Bay\" \/>\n<meta property=\"og:description\" content=\"Makadi Bay Speedboat Rental to Dolphin House &amp; Orange bay Island | Barche private di lusso con biglietti, snorkeling, bevande e trasferimento.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hurghadalovers.com\/it\/tours\/makadi-bay-noleggio-di-motoscafi-per-la-casa-dei-delfini-orange-bay-isola\/\" \/>\n<meta property=\"og:site_name\" content=\"Hurghada Excursions &amp; Day Trips | Booking Best Prices Tours\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Hurghadaloversegypt\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-08T09:39:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hurghadalovers.com\/wp-content\/uploads\/2023\/08\/Makadi-Bay-Speedboat-Rental-to-Dolphin-House-Orange-bay-Island.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1156\" \/>\n\t<meta property=\"og:image:height\" content=\"867\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Prezzo\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;&nbsp;230\" \/>\n\t<meta name=\"twitter:label2\" content=\"Disponibilit\u00e0\" \/>\n\t<meta name=\"twitter:data2\" content=\"In stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\/\/hurghadalovers.com\/it\/tours\/makadi-bay-noleggio-di-motoscafi-per-la-casa-dei-delfini-orange-bay-isola\/\",\"url\":\"https:\/\/hurghadalovers.com\/it\/tours\/makadi-bay-noleggio-di-motoscafi-per-la-casa-dei-delfini-orange-bay-isola\/\",\"name\":\"Noleggio motoscafo a Makadi Bay per Dolphin House e Orange Bay\",\"isPartOf\":{\"@id\":\"https:\/\/hurghadalovers.com\/it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/hurghadalovers.com\/it\/tours\/makadi-bay-noleggio-di-motoscafi-per-la-casa-dei-delfini-orange-bay-isola\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/hurghadalovers.com\/it\/tours\/makadi-bay-noleggio-di-motoscafi-per-la-casa-dei-delfini-orange-bay-isola\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/hurghadalovers.com\/wp-content\/uploads\/2023\/08\/Makadi-Bay-Speedboat-Rental-to-Dolphin-House-Orange-bay-Island.jpeg\",\"datePublished\":\"2023-08-30T09:57:07+00:00\",\"dateModified\":\"2026-02-08T09:39:03+00:00\",\"description\":\"Makadi Bay Speedboat Rental to Dolphin House & Orange bay Island | Barche private di lusso con biglietti, snorkeling, bevande e trasferimento.\",\"breadcrumb\":{\"@id\":\"https:\/\/hurghadalovers.com\/it\/tours\/makadi-bay-noleggio-di-motoscafi-per-la-casa-dei-delfini-orange-bay-isola\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/hurghadalovers.com\/it\/tours\/makadi-bay-noleggio-di-motoscafi-per-la-casa-dei-delfini-orange-bay-isola\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/hurghadalovers.com\/it\/tours\/makadi-bay-noleggio-di-motoscafi-per-la-casa-dei-delfini-orange-bay-isola\/#primaryimage\",\"url\":\"https:\/\/hurghadalovers.com\/wp-content\/uploads\/2023\/08\/Makadi-Bay-Speedboat-Rental-to-Dolphin-House-Orange-bay-Island.jpeg\",\"contentUrl\":\"https:\/\/hurghadalovers.com\/wp-content\/uploads\/2023\/08\/Makadi-Bay-Speedboat-Rental-to-Dolphin-House-Orange-bay-Island.jpeg\",\"width\":1156,\"height\":867,\"caption\":\"Noleggio motoscafo nella baia di Makadi per la Dolphin House e l'isola di Orange Bay\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/hurghadalovers.com\/it\/tours\/makadi-bay-noleggio-di-motoscafi-per-la-casa-dei-delfini-orange-bay-isola\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/hurghadalovers.com\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/hurghadalovers.com\/shop\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Noleggio motoscafo nella baia di Makadi per la Dolphin House e l&#8217;isola di Orange Bay\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/hurghadalovers.com\/it\/#website\",\"url\":\"https:\/\/hurghadalovers.com\/it\/\",\"name\":\"Hurghada Excursions & Day Trips | Booking Best Prices Tours\",\"description\":\"Hurghada Lovers - Best Tour Operator - Excursions &amp; Things to do for Family Day Trips with kids and Couples Romantic. Unique .Hidden gems\",\"publisher\":{\"@id\":\"https:\/\/hurghadalovers.com\/it\/#organization\"},\"alternateName\":\"Hurghada Excursions\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/hurghadalovers.com\/it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\",\"TravelAgency\"],\"@id\":\"https:\/\/hurghadalovers.com\/it\/#organization\",\"name\":\"Hurghada Excursions\",\"url\":\"https:\/\/hurghadalovers.com\/it\/\",\"logo\":{\"@id\":\"https:\/\/hurghadalovers.com\/it\/tours\/makadi-bay-noleggio-di-motoscafi-per-la-casa-dei-delfini-orange-bay-isola\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\/\/hurghadalovers.com\/it\/tours\/makadi-bay-noleggio-di-motoscafi-per-la-casa-dei-delfini-orange-bay-isola\/#local-main-organization-logo\"},\"sameAs\":[\"https:\/\/www.facebook.com\/Hurghadaloversegypt\"],\"address\":{\"@id\":\"https:\/\/hurghadalovers.com\/it\/tours\/makadi-bay-noleggio-di-motoscafi-per-la-casa-dei-delfini-orange-bay-isola\/#local-main-place-address\"},\"telephone\":[\"00201112596434\"],\"contactPoint\":{\"@type\":\"ContactPoint\",\"telephone\":\"00201112596434\",\"email\":\"weyouface@gmail.com\"},\"openingHoursSpecification\":{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"00:00\",\"closes\":\"23:59\"},\"email\":\"weyouface@gmail.com\",\"areaServed\":\"Luxor, Hurghada, El Gouna, Aswan, Sharm El Sheikh, Giza, Alexandria, Marsa Alam, Quseir, Soma Bay, Sahl Hasheesh, Red Sea, Makadi Bay, Cairo\",\"priceRange\":\"$\",\"currenciesAccepted\":\"euro\",\"paymentAccepted\":\"cash on site\"},{\"@type\":\"PostalAddress\",\"@id\":\"https:\/\/hurghadalovers.com\/it\/tours\/makadi-bay-noleggio-di-motoscafi-per-la-casa-dei-delfini-orange-bay-isola\/#local-main-place-address\",\"streetAddress\":\"17 Banks street, Alkawther area, top nbk bank\",\"addressLocality\":\"hurghada\",\"postalCode\":\"84511\",\"addressRegion\":\"red sea\",\"addressCountry\":\"EG\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/hurghadalovers.com\/it\/tours\/makadi-bay-noleggio-di-motoscafi-per-la-casa-dei-delfini-orange-bay-isola\/#local-main-organization-logo\",\"url\":\"https:\/\/hurghadalovers.com\/wp-content\/uploads\/2019\/10\/hurghada-excursions-logo.png\",\"contentUrl\":\"https:\/\/hurghadalovers.com\/wp-content\/uploads\/2019\/10\/hurghada-excursions-logo.png\",\"width\":272,\"height\":90,\"caption\":\"Hurghada Excursions\"}]}<\/script>\n<meta property=\"product:brand\" content=\"Escursioni Makadi bay\" \/>\n<meta property=\"product:price:amount\" content=\"230\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"MakadiSnorkeling102024\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<meta name=\"geo.placename\" content=\"hurghada\" \/>\n<meta name=\"geo.region\" content=\"Egitto\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Noleggio motoscafo a Makadi Bay per Dolphin House e Orange Bay","description":"Makadi Bay Speedboat Rental to Dolphin House & Orange bay Island | Barche private di lusso con biglietti, snorkeling, bevande e trasferimento.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hurghadalovers.com\/it\/tours\/makadi-bay-noleggio-di-motoscafi-per-la-casa-dei-delfini-orange-bay-isola\/","og_locale":"it_IT","og_type":"article","og_title":"Noleggio motoscafo nella baia di Makadi per la Dolphin House e l'isola di Orange Bay","og_description":"Makadi Bay Speedboat Rental to Dolphin House & Orange bay Island | Barche private di lusso con biglietti, snorkeling, bevande e trasferimento.","og_url":"https:\/\/hurghadalovers.com\/it\/tours\/makadi-bay-noleggio-di-motoscafi-per-la-casa-dei-delfini-orange-bay-isola\/","og_site_name":"Hurghada Excursions &amp; Day Trips | Booking Best Prices Tours","article_publisher":"https:\/\/www.facebook.com\/Hurghadaloversegypt","article_modified_time":"2026-02-08T09:39:03+00:00","og_image":[{"width":1156,"height":867,"url":"https:\/\/hurghadalovers.com\/wp-content\/uploads\/2023\/08\/Makadi-Bay-Speedboat-Rental-to-Dolphin-House-Orange-bay-Island.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Prezzo":"&euro;&nbsp;230","Disponibilit\u00e0":"In stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["WebPage","ItemPage"],"@id":"https:\/\/hurghadalovers.com\/it\/tours\/makadi-bay-noleggio-di-motoscafi-per-la-casa-dei-delfini-orange-bay-isola\/","url":"https:\/\/hurghadalovers.com\/it\/tours\/makadi-bay-noleggio-di-motoscafi-per-la-casa-dei-delfini-orange-bay-isola\/","name":"Noleggio motoscafo a Makadi Bay per Dolphin House e Orange Bay","isPartOf":{"@id":"https:\/\/hurghadalovers.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/hurghadalovers.com\/it\/tours\/makadi-bay-noleggio-di-motoscafi-per-la-casa-dei-delfini-orange-bay-isola\/#primaryimage"},"image":{"@id":"https:\/\/hurghadalovers.com\/it\/tours\/makadi-bay-noleggio-di-motoscafi-per-la-casa-dei-delfini-orange-bay-isola\/#primaryimage"},"thumbnailUrl":"https:\/\/hurghadalovers.com\/wp-content\/uploads\/2023\/08\/Makadi-Bay-Speedboat-Rental-to-Dolphin-House-Orange-bay-Island.jpeg","datePublished":"2023-08-30T09:57:07+00:00","dateModified":"2026-02-08T09:39:03+00:00","description":"Makadi Bay Speedboat Rental to Dolphin House & Orange bay Island | Barche private di lusso con biglietti, snorkeling, bevande e trasferimento.","breadcrumb":{"@id":"https:\/\/hurghadalovers.com\/it\/tours\/makadi-bay-noleggio-di-motoscafi-per-la-casa-dei-delfini-orange-bay-isola\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hurghadalovers.com\/it\/tours\/makadi-bay-noleggio-di-motoscafi-per-la-casa-dei-delfini-orange-bay-isola\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/hurghadalovers.com\/it\/tours\/makadi-bay-noleggio-di-motoscafi-per-la-casa-dei-delfini-orange-bay-isola\/#primaryimage","url":"https:\/\/hurghadalovers.com\/wp-content\/uploads\/2023\/08\/Makadi-Bay-Speedboat-Rental-to-Dolphin-House-Orange-bay-Island.jpeg","contentUrl":"https:\/\/hurghadalovers.com\/wp-content\/uploads\/2023\/08\/Makadi-Bay-Speedboat-Rental-to-Dolphin-House-Orange-bay-Island.jpeg","width":1156,"height":867,"caption":"Noleggio motoscafo nella baia di Makadi per la Dolphin House e l'isola di Orange Bay"},{"@type":"BreadcrumbList","@id":"https:\/\/hurghadalovers.com\/it\/tours\/makadi-bay-noleggio-di-motoscafi-per-la-casa-dei-delfini-orange-bay-isola\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/hurghadalovers.com\/it\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/hurghadalovers.com\/shop\/"},{"@type":"ListItem","position":3,"name":"Noleggio motoscafo nella baia di Makadi per la Dolphin House e l&#8217;isola di Orange Bay"}]},{"@type":"WebSite","@id":"https:\/\/hurghadalovers.com\/it\/#website","url":"https:\/\/hurghadalovers.com\/it\/","name":"Hurghada Excursions & Day Trips | Booking Best Prices Tours","description":"Hurghada Lovers - Best Tour Operator - Excursions &amp; Things to do for Family Day Trips with kids and Couples Romantic. Unique .Hidden gems","publisher":{"@id":"https:\/\/hurghadalovers.com\/it\/#organization"},"alternateName":"Hurghada Excursions","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hurghadalovers.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place","TravelAgency"],"@id":"https:\/\/hurghadalovers.com\/it\/#organization","name":"Hurghada Excursions","url":"https:\/\/hurghadalovers.com\/it\/","logo":{"@id":"https:\/\/hurghadalovers.com\/it\/tours\/makadi-bay-noleggio-di-motoscafi-per-la-casa-dei-delfini-orange-bay-isola\/#local-main-organization-logo"},"image":{"@id":"https:\/\/hurghadalovers.com\/it\/tours\/makadi-bay-noleggio-di-motoscafi-per-la-casa-dei-delfini-orange-bay-isola\/#local-main-organization-logo"},"sameAs":["https:\/\/www.facebook.com\/Hurghadaloversegypt"],"address":{"@id":"https:\/\/hurghadalovers.com\/it\/tours\/makadi-bay-noleggio-di-motoscafi-per-la-casa-dei-delfini-orange-bay-isola\/#local-main-place-address"},"telephone":["00201112596434"],"contactPoint":{"@type":"ContactPoint","telephone":"00201112596434","email":"weyouface@gmail.com"},"openingHoursSpecification":{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"00:00","closes":"23:59"},"email":"weyouface@gmail.com","areaServed":"Luxor, Hurghada, El Gouna, Aswan, Sharm El Sheikh, Giza, Alexandria, Marsa Alam, Quseir, Soma Bay, Sahl Hasheesh, Red Sea, Makadi Bay, Cairo","priceRange":"$","currenciesAccepted":"euro","paymentAccepted":"cash on site"},{"@type":"PostalAddress","@id":"https:\/\/hurghadalovers.com\/it\/tours\/makadi-bay-noleggio-di-motoscafi-per-la-casa-dei-delfini-orange-bay-isola\/#local-main-place-address","streetAddress":"17 Banks street, Alkawther area, top nbk bank","addressLocality":"hurghada","postalCode":"84511","addressRegion":"red sea","addressCountry":"EG"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/hurghadalovers.com\/it\/tours\/makadi-bay-noleggio-di-motoscafi-per-la-casa-dei-delfini-orange-bay-isola\/#local-main-organization-logo","url":"https:\/\/hurghadalovers.com\/wp-content\/uploads\/2019\/10\/hurghada-excursions-logo.png","contentUrl":"https:\/\/hurghadalovers.com\/wp-content\/uploads\/2019\/10\/hurghada-excursions-logo.png","width":272,"height":90,"caption":"Hurghada Excursions"}]},"product_brand":"Escursioni Makadi bay","product_price_amount":"230","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"MakadiSnorkeling102024","product_condition":"new","geo.placename":"hurghada","geo.region":"Egitto"},"_links":{"self":[{"href":"https:\/\/hurghadalovers.com\/it\/wp-json\/wp\/v2\/product\/388223","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hurghadalovers.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/hurghadalovers.com\/it\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hurghadalovers.com\/it\/wp-json\/wp\/v2\/media\/388145"}],"wp:attachment":[{"href":"https:\/\/hurghadalovers.com\/it\/wp-json\/wp\/v2\/media?parent=388223"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/hurghadalovers.com\/it\/wp-json\/wp\/v2\/product_brand?post=388223"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/hurghadalovers.com\/it\/wp-json\/wp\/v2\/product_cat?post=388223"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/hurghadalovers.com\/it\/wp-json\/wp\/v2\/product_tag?post=388223"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}